{"id":173,"count":38,"description":"","link":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries","name":"Travel Itineraries","slug":"travel-itineraries","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel Itineraries - Blog Rentcars<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Itineraries - Blog Rentcars\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries\" \/>\n<meta property=\"og:site_name\" content=\"Blog Rentcars\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries\",\"url\":\"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries\",\"name\":\"Travel Itineraries - Blog Rentcars\",\"isPartOf\":{\"@id\":\"https:\/\/blog.rentcars.com\/en#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.rentcars.com\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel Itineraries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.rentcars.com\/en#website\",\"url\":\"https:\/\/blog.rentcars.com\/en\",\"name\":\"Blog Rentcars\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.rentcars.com\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.rentcars.com\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.rentcars.com\/en#organization\",\"name\":\"Rentcars\",\"url\":\"https:\/\/blog.rentcars.com\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.rentcars.com\/en#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.rentcars.com\/wp-content\/uploads\/2023\/05\/blog.rentcars.com-quadrada-positiva-2.png\",\"contentUrl\":\"https:\/\/blog.rentcars.com\/wp-content\/uploads\/2023\/05\/blog.rentcars.com-quadrada-positiva-2.png\",\"width\":842,\"height\":683,\"caption\":\"Rentcars\"},\"image\":{\"@id\":\"https:\/\/blog.rentcars.com\/en#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Itineraries - Blog Rentcars","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries","og_locale":"en_US","og_type":"article","og_title":"Travel Itineraries - Blog Rentcars","og_url":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries","og_site_name":"Blog Rentcars","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries","url":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries","name":"Travel Itineraries - Blog Rentcars","isPartOf":{"@id":"https:\/\/blog.rentcars.com\/en#website"},"breadcrumb":{"@id":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rentcars.com\/en\/category\/travel-itineraries#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.rentcars.com\/en"},{"@type":"ListItem","position":2,"name":"Travel Itineraries"}]},{"@type":"WebSite","@id":"https:\/\/blog.rentcars.com\/en#website","url":"https:\/\/blog.rentcars.com\/en","name":"Blog Rentcars","description":"","publisher":{"@id":"https:\/\/blog.rentcars.com\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.rentcars.com\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.rentcars.com\/en#organization","name":"Rentcars","url":"https:\/\/blog.rentcars.com\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.rentcars.com\/en#\/schema\/logo\/image\/","url":"https:\/\/blog.rentcars.com\/wp-content\/uploads\/2023\/05\/blog.rentcars.com-quadrada-positiva-2.png","contentUrl":"https:\/\/blog.rentcars.com\/wp-content\/uploads\/2023\/05\/blog.rentcars.com-quadrada-positiva-2.png","width":842,"height":683,"caption":"Rentcars"},"image":{"@id":"https:\/\/blog.rentcars.com\/en#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.rentcars.com\/en\/wp-json\/wp\/v2\/categories\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rentcars.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.rentcars.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.rentcars.com\/en\/wp-json\/wp\/v2\/posts?categories=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}